

{"id":2761,"date":"2013-07-26T11:21:49","date_gmt":"2013-07-26T11:21:49","guid":{"rendered":"http:\/\/content.staffsante.fr\/?p=2761"},"modified":"2026-04-22T17:06:08","modified_gmt":"2026-04-22T15:06:08","slug":"exemple-de-cv-ergotherapeute","status":"publish","type":"post","link":"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/","title":{"rendered":"Exemple de CV Ergoth\u00e9rapeute"},"content":{"rendered":"<figure class=\"visucvlettre\"><a title=\"CV Ergoth\u00e9rapeute pdf\" href=\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2013\/07\/CV-Ergoth%C3%A9rapeute.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" src=\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2018\/02\/CV-ergotherapeute.png\" alt=\"CV Ergoth\u00e9rapeute pdf\" width=\"250\" height=\"354\" \/><\/a><figcaption>CV Ergoth\u00e9rapeute<\/figcaption><\/figure>\n<p><span style=\"font-size: medium;\">Le titre<\/span><\/p>\n<p>Dans cet exemple de CV, le titre reprend le nombre d&#8217;ann\u00e9es d&#8217;exp\u00e9rience ainsi que la sp\u00e9cialit\u00e9 du candidat (ergoth\u00e9rapeute pour adultes). Cela permet au recruteur de cibler, d\u00e8s le 1er coup d\u2019\u0153il, l&#8217;objet de la candidature et le profil du candidat. \u00c9videmment, si vous postulez pour travailler aupr\u00e8s d&#8217;enfants, inutile de mentionner dans le titre votre exp\u00e9rience aupr\u00e8s d&#8217;adultes.<!--more--><\/p>\n<p><span style=\"font-size: medium;\">Les exp\u00e9riences professionnelles<\/span><\/p>\n<p>Ne vous contentez pas de lister vos exp\u00e9riences car le recruteur veut bri\u00e8vement apercevoir ce que vous avez accompli et voir ainsi si votre profil correspond \u00e0 ses besoins. C&#8217;est pourquoi, sous chaque exp\u00e9rience professionnelle, le candidat \u00e9num\u00e8re les missions les plus significatives qu&#8217;il a accomplies par le pass\u00e9.<br \/>\nLes stages effectu\u00e9s durant la scolarit\u00e9 du candidat sont \u00e9galement mentionn\u00e9s. Cependant, si vous \u00eates tr\u00e8s exp\u00e9riment\u00e9 et que vous avez multipli\u00e9 les contrats dans diff\u00e9rentes structures, contentez-vous de ne mentionner que les importants. Dans le cas contraire vous risqueriez de noyer le recruteur sous le flot d&#8217;informations. Rappelez-vous qu&#8217;un CV ne doit pas faire plus d&#8217;un recto. Un recto-verso est tol\u00e9r\u00e9 si vous avez de nombreuses ann\u00e9es d&#8217;exp\u00e9rience.<\/p>\n<p><span style=\"font-size: medium;\">Les informations compl\u00e9mentaires<\/span><\/p>\n<p>Vous \u00eates nombreux \u00e0 n\u00e9gliger la rubrique des &#8220;informations compl\u00e9mentaires&#8221;. Pourtant, apr\u00e8s la lecture des exp\u00e9riences et des formations, cette rubrique peut confirmer au recruteur la bonne opinion qu&#8217;il se fait de vous.<br \/>\nIci, par exemple, le candidat mentionne l&#8217;obtention de l&#8217;Attestation de Formation aux Gestes et Soins d&#8217;Urgence niveau 2 (AFGSU2), c&#8217;est un v\u00e9ritable atout quand on s&#8217;occupe de patients handicap\u00e9s.<br \/>\nEnfin, si vous \u00eates b\u00e9n\u00e9vole dans une association, n&#8217;h\u00e9sitez pas \u00e0 le mentionner. Cela montrera au recruteur que vous \u00eates une personne impliqu\u00e9e.<\/p>\n<p style=\"text-align: left;\"><strong>L\u00e9o BASIN<\/strong> (28 ans)<br \/>\n13 rue de la Libert\u00e9<br \/>\n34000 Montpellier<br \/>\n06 00 00 00 00<br \/>\nleo.basin@ergoth\u00e9rapeute.fr<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"text-decoration: underline;\"><span style=\"color: #3366ff; text-decoration: underline;\">Ergoth\u00e9rapeute : 6 ans d&#8217;exp\u00e9rience aupr\u00e8s d&#8217;adultes<\/span><\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #3366ff;\">Exp\u00e9riences professionnelles<\/span><\/p>\n<p><em><strong>De septembre 2010 \u00e0 juin 2013<\/strong><\/em> : Ergoth\u00e9rapeute, Service de m\u00e9decine et de r\u00e9adaptation du CHU de Montpellier<\/p>\n<ul>\n<li>R\u00e9\u00e9ducation fonctionnelle chez l&#8217;adulte<\/li>\n<li>R\u00e9adaptation neurologique<\/li>\n<li>Suivi et bilan individuels<\/li>\n<li>Appareillage<\/li>\n<li>Encadrement de stagiaires<\/li>\n<\/ul>\n<p><em><strong>De mars 2008 \u00e0 septembre 2010<\/strong><\/em> : Ergoth\u00e9rapeute, Foyer de vie &#8220;Bassin de Thau Jean Piaget&#8221; de Frontignan<\/p>\n<ul>\n<li>R\u00e9adaptation d&#8217;adultes polyhandicap\u00e9s<\/li>\n<li>R\u00e9\u00e9ducation fonctionnelle (neurologie et orthop\u00e9die)<\/li>\n<li>Suivi individuel<\/li>\n<li>Appareillage<\/li>\n<li>Mise en place d&#8217;activit\u00e9s physiques et manuelles<\/li>\n<\/ul>\n<p><em><strong>De juillet 2007 \u00e0 janvier 2008<\/strong><\/em> : Ergoth\u00e9rapeute, Atelier Th\u00e9rapeutique Occupationnel &#8220;Les Terres Blanches&#8221; de Montpellier<\/p>\n<ul>\n<li>R\u00e9\u00e9ducation orthop\u00e9dique des adultes handicap\u00e9s<\/li>\n<li>D\u00e9veloppement de l&#8217;autonomie<\/li>\n<li>Mise en place d&#8217;activit\u00e9s physiques et manuelles<\/li>\n<\/ul>\n<p><em><strong>De f\u00e9vrier \u00e0 avril 2007<\/strong><\/em> : Ergoth\u00e9rapeute, Foyer de vie &#8220;Villa Marquerose&#8221; de Montpellier (Stage)<\/p>\n<p><em><strong>De janvier \u00e0 mars et de mai \u00e0 juillet 2006<\/strong><\/em> : Ergoth\u00e9rapeute, Service d&#8217;Accompagnement M\u00e9dico-Social pour Adultes Handicap\u00e9s &#8220;Les Vents du Sud&#8221; de Montpellier (Stage)<\/p>\n<p><em><strong>De mars \u00e0 avril 2005<\/strong><\/em> : Ergoth\u00e9rapeute, &#8220;Maison Perce-Neige&#8221; de Montpellier (Stage)<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #3366ff;\">Formation<\/span><\/p>\n<ul>\n<li><span style=\"line-height: 13px;\"><em><strong>2006<\/strong><\/em> : Obtention du Dipl\u00f4me d&#8217;\u00c9tat d&#8217;Ergoth\u00e9rapeute<\/span><\/li>\n<li><em><strong>2004 &#8211; 2007<\/strong><\/em> : Pr\u00e9paration du Dipl\u00f4me d&#8217;\u00c9tat d&#8217;Ergoth\u00e9rapeute \u00e0 l&#8217;Institut de Formation d&#8217;Ergoth\u00e9rapie de Montpellier<\/li>\n<li><em><strong>2003 &#8211; 2004<\/strong><\/em> : Premi\u00e8re Ann\u00e9e Commune aux \u00c9tudes de Sant\u00e9 \u00e0 la facult\u00e9 de m\u00e9decine de Montpellier<\/li>\n<li><em><strong>2003<\/strong><\/em> : Obtention du Baccalaur\u00e9at Scientifique<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><span style=\"color: #3366ff;\">Informations compl\u00e9mentaires<\/span><\/p>\n<ul>\n<li><span style=\"line-height: 13px;\">Attestation de Formation aux Gestes et Soins d&#8217;Urgence niveau 2<\/span><\/li>\n<li>Poss\u00e8de le permis B et un v\u00e9hicule<\/li>\n<li>B\u00e9n\u00e9vole au sein de l&#8217;association &#8220;\u00c0 bras ouverts&#8221; (organisation de s\u00e9jours pour enfants et adolescents handicap\u00e9s)<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><span style=\"color: #3366ff;\">Centres d&#8217;int\u00e9r\u00eat<\/span><\/p>\n<ul>\n<li><span style=\"line-height: 13px;\">Peinture<\/span><\/li>\n<li>Handball en club (depuis 9 ans)<\/li>\n<\/ul>\n<p>T\u00e9l\u00e9charger le mod\u00e8le de CV ergoth\u00e9rapeute en format pdf :\u00a0<a class=\"telechargement_CV_pdf\" href=\"https:\/\/www.staffsante.fr\/contenu\/wp-content\/uploads\/2013\/07\/CV-Ergoth\u00e9rapeute.pdf\">CV Ergoth\u00e9rapeute<\/a>.<\/p>\n<p>T\u00e9l\u00e9charger le mod\u00e8le de CV ergoth\u00e9rapeute en format doc :\u00a0<a class=\"telechargement_CV_doc\" href=\"https:\/\/www.staffsante.fr\/contenu\/wp-content\/uploads\/2013\/07\/CV-Ergoth\u00e9rapeute.doc\">CV Ergoth\u00e9rapeute<\/a>.<\/p>\n<p><a href=\"https:\/\/www.staffsocial.fr\/recherche?utf8=%E2%9C%93&amp;types_contrat=job_offer&amp;quoi=ergoth%C3%A9rapeute&amp;ou=\"><img loading=\"lazy\" class=\"size-full wp-image-3114 aligncenter\" src=\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2013\/11\/lettre_ergotherapeute_ok.png\" alt=\"lettre_ergotherapeute_ok\" width=\"138\" height=\"54\" \/><\/a><\/p>\n<h2>Quelques offres d&#8217;emploi d&#8217;ergoth\u00e9rapeute<\/h2>\n<div id=\"result_extract\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>CV Ergoth\u00e9rapeute Le titre Dans cet exemple de CV, le titre reprend le nombre d&#8217;ann\u00e9es d&#8217;exp\u00e9rience ainsi que la sp\u00e9cialit\u00e9 du candidat (ergoth\u00e9rapeute pour adultes). Cela permet au recruteur de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[313,17,22,335,50,316,214,32,260,160,9,112,46],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exemple de CV Ergoth\u00e9rapeute | STAFFSANT\u00c9<\/title>\n<meta name=\"description\" content=\"CV Ergoth\u00e9rapeute Le titre Dans cet exemple de CV, le titre reprend le nombre d&#039;ann\u00e9es d&#039;exp\u00e9rience ainsi que la sp\u00e9cialit\u00e9 du candidat (ergoth\u00e9rapeute\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exemple de CV Ergoth\u00e9rapeute | STAFFSANT\u00c9\" \/>\n<meta property=\"og:description\" content=\"CV Ergoth\u00e9rapeute Le titre Dans cet exemple de CV, le titre reprend le nombre d&#039;ann\u00e9es d&#039;exp\u00e9rience ainsi que la sp\u00e9cialit\u00e9 du candidat (ergoth\u00e9rapeute\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/\" \/>\n<meta property=\"og:site_name\" content=\"STAFFSANT\u00c9\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-26T11:21:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T15:06:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2018\/02\/CV-ergotherapeute.png\" \/>\n<meta name=\"author\" content=\"admin_staff_content\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_staff_content\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/\"},\"author\":{\"name\":\"admin_staff_content\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/8cea5b012277ab5dd4995aec10f20b0c\"},\"headline\":\"Exemple de CV Ergoth\u00e9rapeute\",\"datePublished\":\"2013-07-26T11:21:49+00:00\",\"dateModified\":\"2026-04-22T15:06:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/\"},\"wordCount\":620,\"publisher\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#organization\"},\"keywords\":[\"conseil\",\"CV\",\"Emploi\",\"ergoth\u00e9rapeute\",\"\u00e9tablissement de sant\u00e9\",\"Exemple\",\"Job\",\"recherche d'emploi\",\"recrutement\",\"recruteurs\",\"Sant\u00e9\",\"Staffsant\u00e9\",\"travail\"],\"articleSection\":[\"Exemples de CV et de lettres de motivation\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/\",\"url\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/\",\"name\":\"Exemple de CV Ergoth\u00e9rapeute | STAFFSANT\u00c9\",\"isPartOf\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#website\"},\"datePublished\":\"2013-07-26T11:21:49+00:00\",\"dateModified\":\"2026-04-22T15:06:08+00:00\",\"description\":\"CV Ergoth\u00e9rapeute Le titre Dans cet exemple de CV, le titre reprend le nombre d'ann\u00e9es d'exp\u00e9rience ainsi que la sp\u00e9cialit\u00e9 du candidat (ergoth\u00e9rapeute\",\"breadcrumb\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.staffsante.fr\/contenu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exemple de CV Ergoth\u00e9rapeute\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#website\",\"url\":\"https:\/\/www.staffsante.fr\/contenu\/\",\"name\":\"STAFFSANT\u00c9\",\"description\":\"L&#039;actualit\u00e9 carri\u00e8re des professionnels de sant\u00e9\",\"publisher\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.staffsante.fr\/contenu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#organization\",\"name\":\"Staffsant\u00e9\",\"url\":\"https:\/\/www.staffsante.fr\/contenu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2017\/06\/Staffsante.jpg\",\"contentUrl\":\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2017\/06\/Staffsante.jpg\",\"width\":2225,\"height\":592,\"caption\":\"Staffsant\u00e9\"},\"image\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/8cea5b012277ab5dd4995aec10f20b0c\",\"name\":\"admin_staff_content\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/2b9ac03912eb39091678a45d1b4c36c0?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/2b9ac03912eb39091678a45d1b4c36c0?s=96&d=mm&r=g\",\"caption\":\"admin_staff_content\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exemple de CV Ergoth\u00e9rapeute | STAFFSANT\u00c9","description":"CV Ergoth\u00e9rapeute Le titre Dans cet exemple de CV, le titre reprend le nombre d'ann\u00e9es d'exp\u00e9rience ainsi que la sp\u00e9cialit\u00e9 du candidat (ergoth\u00e9rapeute","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/","og_locale":"fr_FR","og_type":"article","og_title":"Exemple de CV Ergoth\u00e9rapeute | STAFFSANT\u00c9","og_description":"CV Ergoth\u00e9rapeute Le titre Dans cet exemple de CV, le titre reprend le nombre d'ann\u00e9es d'exp\u00e9rience ainsi que la sp\u00e9cialit\u00e9 du candidat (ergoth\u00e9rapeute","og_url":"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/","og_site_name":"STAFFSANT\u00c9","article_published_time":"2013-07-26T11:21:49+00:00","article_modified_time":"2026-04-22T15:06:08+00:00","og_image":[{"url":"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2018\/02\/CV-ergotherapeute.png"}],"author":"admin_staff_content","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin_staff_content","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/#article","isPartOf":{"@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/"},"author":{"name":"admin_staff_content","@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/8cea5b012277ab5dd4995aec10f20b0c"},"headline":"Exemple de CV Ergoth\u00e9rapeute","datePublished":"2013-07-26T11:21:49+00:00","dateModified":"2026-04-22T15:06:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/"},"wordCount":620,"publisher":{"@id":"https:\/\/www.staffsante.fr\/contenu\/#organization"},"keywords":["conseil","CV","Emploi","ergoth\u00e9rapeute","\u00e9tablissement de sant\u00e9","Exemple","Job","recherche d'emploi","recrutement","recruteurs","Sant\u00e9","Staffsant\u00e9","travail"],"articleSection":["Exemples de CV et de lettres de motivation"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/","url":"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/","name":"Exemple de CV Ergoth\u00e9rapeute | STAFFSANT\u00c9","isPartOf":{"@id":"https:\/\/www.staffsante.fr\/contenu\/#website"},"datePublished":"2013-07-26T11:21:49+00:00","dateModified":"2026-04-22T15:06:08+00:00","description":"CV Ergoth\u00e9rapeute Le titre Dans cet exemple de CV, le titre reprend le nombre d'ann\u00e9es d'exp\u00e9rience ainsi que la sp\u00e9cialit\u00e9 du candidat (ergoth\u00e9rapeute","breadcrumb":{"@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-de-cv-ergotherapeute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.staffsante.fr\/contenu\/"},{"@type":"ListItem","position":2,"name":"Exemple de CV Ergoth\u00e9rapeute"}]},{"@type":"WebSite","@id":"https:\/\/www.staffsante.fr\/contenu\/#website","url":"https:\/\/www.staffsante.fr\/contenu\/","name":"STAFFSANT\u00c9","description":"L&#039;actualit\u00e9 carri\u00e8re des professionnels de sant\u00e9","publisher":{"@id":"https:\/\/www.staffsante.fr\/contenu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.staffsante.fr\/contenu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.staffsante.fr\/contenu\/#organization","name":"Staffsant\u00e9","url":"https:\/\/www.staffsante.fr\/contenu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/logo\/image\/","url":"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2017\/06\/Staffsante.jpg","contentUrl":"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2017\/06\/Staffsante.jpg","width":2225,"height":592,"caption":"Staffsant\u00e9"},"image":{"@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/8cea5b012277ab5dd4995aec10f20b0c","name":"admin_staff_content","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/2b9ac03912eb39091678a45d1b4c36c0?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/2b9ac03912eb39091678a45d1b4c36c0?s=96&d=mm&r=g","caption":"admin_staff_content"}}]}},"_links":{"self":[{"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/posts\/2761"}],"collection":[{"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/comments?post=2761"}],"version-history":[{"count":8,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/posts\/2761\/revisions"}],"predecessor-version":[{"id":12959,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/posts\/2761\/revisions\/12959"}],"wp:attachment":[{"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/media?parent=2761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/categories?post=2761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/tags?post=2761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}