

{"id":4550,"date":"2018-02-07T16:44:35","date_gmt":"2018-02-07T15:44:35","guid":{"rendered":"http:\/\/content.staffsante.fr\/?p=4550"},"modified":"2026-04-22T16:53:49","modified_gmt":"2026-04-22T14:53:49","slug":"exemple-lettre-de-motivation-opticien-lunetier","status":"publish","type":"post","link":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/","title":{"rendered":"Exemple de lettre de motivation opticien(ne)-lunetier(i\u00e8re)"},"content":{"rendered":"<figure class=\"visucvlettre\"><a title=\"Lettre de motivation opticien(ne)-lunetier(i\u00e8re) doc\" href=\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2018\/02\/lettre-de-motivation-opticien.doc\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" src=\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2018\/02\/lettre-de-motivation-opticien-large.png\" alt=\"Lettre de motivation opticien(ne)-lunetier(i\u00e8re) doc\" width=\"250\" height=\"354\" \/><\/a><figcaption>Lettre de motivation opticien(ne)-lunetier(i\u00e8re)<\/figcaption><\/figure>\n<p>La lettre de motivation d\u2019un opticien(ne)-lunetier(i\u00e8re) doit pr\u00e9senter ses comp\u00e9tences techniques mais aussi sa capacit\u00e9 \u00e0 conseiller et vendre. En effet, l\u2019opticien ; titulaire d\u2019un BTS opticien-lunetier, est un v\u00e9ritable professionnel de la sant\u00e9 mais aussi un vendeur capable de conseiller les clients sur l\u2019esth\u00e9tisme et le confort des montures.<\/p>\n<p>Il r\u00e9alise les lunettes souvent en s\u2019appuyant sur la prescription de l\u2019ophtalmologiste, cependant il est capable d\u2019\u00e9valuer l\u2019acuit\u00e9 visuelle en r\u00e9alisant un examen optom\u00e9trique. Il conseille le client selon ses habitudes et sa morphologie afin de lui proposer des lunettes (ou des lentilles) adapt\u00e9es. L\u2019opticien est aussi en charge de l\u2019apr\u00e8s-vente et effectue donc des r\u00e9parations : branches cass\u00e9es, r\u00e9glages ou encore le changement de verres.<\/p>\n<p>La lettre de motivation d\u2019un opticien(ne)-lunetier(i\u00e8re) doit \u00eatre personnalis\u00e9e pour chaque \u00e9tablissement. Il est important d\u2019y pr\u00e9senter les raisons pour lesquelles vous avez s\u00e9lectionn\u00e9 cet opticien et pas un autre.<\/p>\n<p>Nous vous proposons ici un exemple, un mod\u00e8le de lettre de motivation pour opticien(ne)-lunetier(i\u00e8re).<\/p>\n<p>Comme pour chaque lettre de motivation, vous pouvez adopter cette structure :<\/p>\n<h2>Parlez de l\u2019opticien-lunetier<\/h2>\n<p>Pr\u00e9sentez ici les connaissances que vous avez en tant que professionnel sur l\u2019opticien-lunetier. Indiquez ici la situation actuelle g\u00e9n\u00e9rale de votre candidature : notori\u00e9t\u00e9 du point de vente, sp\u00e9cialisations, certifications (AFNOR). Vous pouvez aussi introduire votre situation actuelle : fraichement dipl\u00f4m\u00e9, \u00e0 la recherche de nouveaux d\u00e9fis&#8230;Vous devez indiquer les raisons qui vous poussent \u00e0 postuler \u00e0 cette offre.<\/p>\n<h2>Parlez de vous : l\u2019opticien(ne)-lunetier(i\u00e8re)<\/h2>\n<p>L\u2019objectif de ce paragraphe est de vous pr\u00e9senter en tant qu\u2019opticien(ne)-lunetier(i\u00e8re). Indiquez ici de mani\u00e8re sp\u00e9cifique vos exp\u00e9riences marquantes ou encore votre savoir-faire dans certains domaines. Attention toutefois, il ne faut pas r\u00e9p\u00e9ter votre CV dans ce paragraphe. N\u2019h\u00e9sitez pas \u00e0 consulter les missions de l\u2019offre d\u2019emploi afin de lister les attentes du recruteur et d\u2019y r\u00e9pondre dans cette partie. Le but est ici de vous vendre !<\/p>\n<h2>Parlez de vous : l\u2019opticien(ne)-lunetier(i\u00e8re) et l\u2019\u00e9tablissement<\/h2>\n<p>Cette derni\u00e8re partie doit pr\u00e9senter ce que vous pouvez faire ensemble. Ce que le recruteur peut vous apporter et ce que vous pouvez apporter au recruteur. Il faut ici susciter l\u2019int\u00e9r\u00eat de l\u2019opticien-lunetier. Nous vous conseillons donc d\u2019indiquer par exemple une proc\u00e9dure de travail qui vous est propre, une comp\u00e9tence accrue dans certains domaines comme le conseil, la vente ou encore l\u2019examen optom\u00e9trique. Consultez notre mod\u00e8le de lettre de motivation d\u2019opticien(ne)-lunetier(i\u00e8re) pour vous donner de l\u2019inspiration.<\/p>\n<h2>Les \u00e9l\u00e9ments \u00e0 \u00e9viter<\/h2>\n<ul>\n<li>les phrases trop longues : le temps du recruteur est compt\u00e9, allez donc \u00e0 l\u2019essentiel<\/li>\n<li>une lettre de motivation trop longue : cela doit tenir sur une page trop d\u2019\u00e9loges ou de banalit\u00e9s<\/li>\n<li>r\u00e9p\u00e9ter votre CV<\/li>\n<li>les fautes de syntaxe et d\u2019orthographes<\/li>\n<li>les erreurs sur l&#8217;entreprise : v\u00e9rifiez vos informations<\/li>\n<\/ul>\n<p>T\u00e9l\u00e9charger le mod\u00e8le de lettre de motivation Opticien en format doc : <a class=\"telechargement_LM_doc\" title=\"Notre exemple de lettre de motivation en .doc\" href=\"https:\/\/www.staffsante.fr\/contenu\/wp-content\/uploads\/2018\/02\/lettre-de-motivation-opticien.doc\">Exemple lettre de motivation Opticien<\/a><\/p>\n<p>Votre lettre de motivation d\u2019opticien(ne)-lunetier(i\u00e8re) est termin\u00e9e ? Consultez alors toutes les <a title=\"Pr\u00eat? Postulez \u00e0 nos offres d'emplois pour Opticien\" href=\"https:\/\/www.staffsante.fr\/offres-emploi-m-opticien\">offres d\u2019emploi d\u2019opticien(ne)-lunetier(i\u00e8re)<\/a> et postulez !<\/p>\n<p>Besoin d\u2019un bon exemple de CV pour opticien(ne)-lunetier(i\u00e8re)? Consultez notre <a title=\"Notre exemple de lettre de motivation en .pdf\" href=\"https:\/\/content.staffsante.fr\/exemple-modele-de-cv-opticien\/\">mod\u00e8le de CV pour Opticien<\/a> d\u00e8s maintenant.<\/p>\n<h2>Trouvez votre prochain emploi d&#8217;opticien<\/h2>\n<div id=\"result_extract\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lettre de motivation opticien(ne)-lunetier(i\u00e8re) La lettre de motivation d\u2019un opticien(ne)-lunetier(i\u00e8re) doit pr\u00e9senter ses comp\u00e9tences techniques mais aussi sa capacit\u00e9 \u00e0 conseiller et vendre. En effet, l\u2019opticien ; titulaire d\u2019un BTS [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[303,105],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exemple de lettre de motivation opticien | STAFFSANT\u00c9<\/title>\n<meta name=\"description\" content=\"Besoin d\u2019aide pour r\u00e9diger votre lettre de motivation d\u2019Opticien-lunetier\u00a0? D\u00e9couvrez notre exemple en ligne\u00a0: des conseils de r\u00e9daction, les qualit\u00e9s requises pour une lettre simple et efficace qui fera mouche \u00e0 tous les coups\u00a0!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exemple de lettre de motivation opticien | STAFFSANT\u00c9\" \/>\n<meta property=\"og:description\" content=\"Besoin d\u2019aide pour r\u00e9diger votre lettre de motivation d\u2019Opticien-lunetier\u00a0? D\u00e9couvrez notre exemple en ligne\u00a0: des conseils de r\u00e9daction, les qualit\u00e9s requises pour une lettre simple et efficace qui fera mouche \u00e0 tous les coups\u00a0!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/\" \/>\n<meta property=\"og:site_name\" content=\"STAFFSANT\u00c9\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-07T15:44:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T14:53:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2018\/02\/lettre-de-motivation-opticien-large.png\" \/>\n<meta name=\"author\" content=\"admin_staff_content\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_staff_content\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/\"},\"author\":{\"name\":\"admin_staff_content\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/8cea5b012277ab5dd4995aec10f20b0c\"},\"headline\":\"Exemple de lettre de motivation opticien(ne)-lunetier(i\u00e8re)\",\"datePublished\":\"2018-02-07T15:44:35+00:00\",\"dateModified\":\"2026-04-22T14:53:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/\"},\"wordCount\":625,\"publisher\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#organization\"},\"keywords\":[\"lettre de motivation\",\"postuler\"],\"articleSection\":[\"Exemples de CV et de lettres de motivation\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/\",\"url\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/\",\"name\":\"Exemple de lettre de motivation opticien | STAFFSANT\u00c9\",\"isPartOf\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#website\"},\"datePublished\":\"2018-02-07T15:44:35+00:00\",\"dateModified\":\"2026-04-22T14:53:49+00:00\",\"description\":\"Besoin d\u2019aide pour r\u00e9diger votre lettre de motivation d\u2019Opticien-lunetier\u00a0? D\u00e9couvrez notre exemple en ligne\u00a0: des conseils de r\u00e9daction, les qualit\u00e9s requises pour une lettre simple et efficace qui fera mouche \u00e0 tous les coups\u00a0!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.staffsante.fr\/contenu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exemple de lettre de motivation opticien(ne)-lunetier(i\u00e8re)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#website\",\"url\":\"https:\/\/www.staffsante.fr\/contenu\/\",\"name\":\"STAFFSANT\u00c9\",\"description\":\"L&#039;actualit\u00e9 carri\u00e8re des professionnels de sant\u00e9\",\"publisher\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.staffsante.fr\/contenu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#organization\",\"name\":\"Staffsant\u00e9\",\"url\":\"https:\/\/www.staffsante.fr\/contenu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2017\/06\/Staffsante.jpg\",\"contentUrl\":\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2017\/06\/Staffsante.jpg\",\"width\":2225,\"height\":592,\"caption\":\"Staffsant\u00e9\"},\"image\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/8cea5b012277ab5dd4995aec10f20b0c\",\"name\":\"admin_staff_content\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/2b9ac03912eb39091678a45d1b4c36c0?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/2b9ac03912eb39091678a45d1b4c36c0?s=96&d=mm&r=g\",\"caption\":\"admin_staff_content\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exemple de lettre de motivation opticien | STAFFSANT\u00c9","description":"Besoin d\u2019aide pour r\u00e9diger votre lettre de motivation d\u2019Opticien-lunetier\u00a0? D\u00e9couvrez notre exemple en ligne\u00a0: des conseils de r\u00e9daction, les qualit\u00e9s requises pour une lettre simple et efficace qui fera mouche \u00e0 tous les coups\u00a0!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/","og_locale":"fr_FR","og_type":"article","og_title":"Exemple de lettre de motivation opticien | STAFFSANT\u00c9","og_description":"Besoin d\u2019aide pour r\u00e9diger votre lettre de motivation d\u2019Opticien-lunetier\u00a0? D\u00e9couvrez notre exemple en ligne\u00a0: des conseils de r\u00e9daction, les qualit\u00e9s requises pour une lettre simple et efficace qui fera mouche \u00e0 tous les coups\u00a0!","og_url":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/","og_site_name":"STAFFSANT\u00c9","article_published_time":"2018-02-07T15:44:35+00:00","article_modified_time":"2026-04-22T14:53:49+00:00","og_image":[{"url":"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2018\/02\/lettre-de-motivation-opticien-large.png"}],"author":"admin_staff_content","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin_staff_content","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/#article","isPartOf":{"@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/"},"author":{"name":"admin_staff_content","@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/8cea5b012277ab5dd4995aec10f20b0c"},"headline":"Exemple de lettre de motivation opticien(ne)-lunetier(i\u00e8re)","datePublished":"2018-02-07T15:44:35+00:00","dateModified":"2026-04-22T14:53:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/"},"wordCount":625,"publisher":{"@id":"https:\/\/www.staffsante.fr\/contenu\/#organization"},"keywords":["lettre de motivation","postuler"],"articleSection":["Exemples de CV et de lettres de motivation"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/","url":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/","name":"Exemple de lettre de motivation opticien | STAFFSANT\u00c9","isPartOf":{"@id":"https:\/\/www.staffsante.fr\/contenu\/#website"},"datePublished":"2018-02-07T15:44:35+00:00","dateModified":"2026-04-22T14:53:49+00:00","description":"Besoin d\u2019aide pour r\u00e9diger votre lettre de motivation d\u2019Opticien-lunetier\u00a0? D\u00e9couvrez notre exemple en ligne\u00a0: des conseils de r\u00e9daction, les qualit\u00e9s requises pour une lettre simple et efficace qui fera mouche \u00e0 tous les coups\u00a0!","breadcrumb":{"@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-opticien-lunetier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.staffsante.fr\/contenu\/"},{"@type":"ListItem","position":2,"name":"Exemple de lettre de motivation opticien(ne)-lunetier(i\u00e8re)"}]},{"@type":"WebSite","@id":"https:\/\/www.staffsante.fr\/contenu\/#website","url":"https:\/\/www.staffsante.fr\/contenu\/","name":"STAFFSANT\u00c9","description":"L&#039;actualit\u00e9 carri\u00e8re des professionnels de sant\u00e9","publisher":{"@id":"https:\/\/www.staffsante.fr\/contenu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.staffsante.fr\/contenu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.staffsante.fr\/contenu\/#organization","name":"Staffsant\u00e9","url":"https:\/\/www.staffsante.fr\/contenu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/logo\/image\/","url":"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2017\/06\/Staffsante.jpg","contentUrl":"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2017\/06\/Staffsante.jpg","width":2225,"height":592,"caption":"Staffsant\u00e9"},"image":{"@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/8cea5b012277ab5dd4995aec10f20b0c","name":"admin_staff_content","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/2b9ac03912eb39091678a45d1b4c36c0?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/2b9ac03912eb39091678a45d1b4c36c0?s=96&d=mm&r=g","caption":"admin_staff_content"}}]}},"_links":{"self":[{"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/posts\/4550"}],"collection":[{"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/comments?post=4550"}],"version-history":[{"count":8,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/posts\/4550\/revisions"}],"predecessor-version":[{"id":4763,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/posts\/4550\/revisions\/4763"}],"wp:attachment":[{"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/media?parent=4550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/categories?post=4550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/tags?post=4550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}