

{"id":4561,"date":"2018-02-07T16:39:42","date_gmt":"2018-02-07T15:39:42","guid":{"rendered":"http:\/\/content.staffsante.fr\/?p=4561"},"modified":"2026-04-22T16:56:32","modified_gmt":"2026-04-22T14:56:32","slug":"exemple-lettre-de-motivation-pharmacien","status":"publish","type":"post","link":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/","title":{"rendered":"Exemple de lettre de motivation pharmacien\u00a0: officine et hospitalier"},"content":{"rendered":"<figure class=\"visucvlettre\"><a title=\"Lettre de motivation pharmacien pdf\" href=\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2018\/02\/lettre-de-motivation-pharmacien.doc\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" src=\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2018\/02\/lettre-de-motivation-pharmacien.png\" alt=\"Lettre de motivation pharmacien pdf\" width=\"250\" height=\"354\" \/><\/a><figcaption>Lettre de motivation pharmacien<\/figcaption><\/figure>\n<p>Vous recherchez un exemple de lettre de motivation pour pharmacien\u00a0? Retrouvez sur cette page nos conseils et un exemple de lettre de motivation pour une candidature r\u00e9ussie en tant que pharmacien (ou pharmacienne) en officine ou en milieu hospitalier.<\/p>\n<p>Le pharmacien est un acteur important du parcours de soins du patient. En effet, il assure la bonne d\u00e9livrance des m\u00e9dicaments prescrits par le m\u00e9decin et indique toutes les pr\u00e9cisions concernant l\u2019administration de ces derniers (posologie, effets secondaires, contre-indications). Titulaire du Dipl\u00f4me d\u2019\u00c9tat de docteur en pharmacie, ce professionnel de sant\u00e9 conna\u00eet des milliers de produits pharmaceutiques et est donc capable de conseiller chaque patient en prenant en compte son \u00e9tat de sant\u00e9.<\/p>\n<p>Les qualit\u00e9s attendues d\u2019un pharmacien sont\u00a0:<\/p>\n<ul>\n<li>la rigueur et la vigilance, pour la pr\u00e9paration des m\u00e9dicaments prescrits<\/li>\n<li>l\u2019\u00e9coute et le conseil : le pharmacien est aussi un commer\u00e7ant<\/li>\n<li>organisation : indispensable pour la gestion des stocks, la commande et la r\u00e9ception des produits<\/li>\n<li>la discr\u00e9tion : v\u00e9ritable confident dans certains cas, le pharmacien est tenu au secret professionnel<\/li>\n<\/ul>\n<p>La lettre de motivation du pharmacien doit \u00eatre unique pour chaque \u00e9tablissement (pharmacie ou h\u00f4pital). Il est important d\u2019y pr\u00e9senter les raisons pour lesquelles vous avez s\u00e9lectionn\u00e9 cet \u00e9tablissement et pas un autre.<\/p>\n<p>Aussi, nous vous conseillons d\u2019identifier le recruteur, n\u2019h\u00e9sitez pas \u00e0 utiliser les r\u00e9seaux sociaux professionnels comme LinkedIn ou m\u00eame le moteur de recherche Google.<\/p>\n<p>Comme pour chaque lettre de motivation, vous pouvez adopter cette structure\u00a0:<\/p>\n<h2>Parlez de l\u2019officine ou de l\u2019h\u00f4pital<\/h2>\n<p>Cette premi\u00e8re partie doit montrer votre connaissance de la pharmacie en question : sa date de cr\u00e9ation, son personnel, les services propos\u00e9s ou encore le cadre dans lequel vous postulez \u00e0 l\u2019offre d\u2019emploi. Vous devez aussi indiquer les motivations qui vous poussent \u00e0 postuler \u00e0 cette annonce (exemple : cadre de travail, objectifs de l\u2019officine, sp\u00e9cialisation&#8230;).<\/p>\n<h2>Parlez de vous\u00a0: le pharmacien<\/h2>\n<p>Parlez de vous dans ce paragraphe, r\u00e9p\u00e9ter votre CV est inutile, il faut indiquer vos r\u00e9ussites, vos comp\u00e9tences en tant que pharmacien. N\u2019h\u00e9sitez pas \u00e0 reprendre les missions de l\u2019annonce afin de lister les besoins du recruteur et d\u2019y r\u00e9pondre dans ce paragraphe. Le but est ici de marquer le recruteur avec votre candidature !<\/p>\n<h2>Parlez de vous : le pharmacien et la pharmacie<\/h2>\n<p>Ce dernier paragraphe doit pr\u00e9senter ce que vous pouvez faire ensemble. Ce que la pharmacie peut vous apporter et ce que vous pouvez apporter \u00e0 la pharmacie. Il faut ici provoquer l\u2019int\u00e9r\u00eat du recruteur. Nous vous conseillons donc d\u2019indiquer par exemple une comp\u00e9tence accrue. Consultez notre exemple de lettre de motivation de pharmacien pour vous lancer.<\/p>\n<h2>Les \u00e9l\u00e9ments \u00e0 \u00e9viter<\/h2>\n<ul>\n<li>les phrases trop longues : le temps du recruteur est compt\u00e9, allez donc \u00e0 l\u2019essentiel<\/li>\n<li>une lettre de motivation trop longue : cela doit tenir sur une page trop d\u2019\u00e9loges ou de banalit\u00e9s<\/li>\n<li>r\u00e9p\u00e9ter votre CV<\/li>\n<li>les fautes de syntaxe et d\u2019orthographes<\/li>\n<li>les erreurs sur la pharmacie : v\u00e9rifiez vos informations<\/li>\n<\/ul>\n<p>T\u00e9l\u00e9charger le mod\u00e8le de lettre de motivation Pharmacien en format doc : <a class=\"telechargement_LM_doc\" title=\"Notre exemple de lettre de motivation en .doc\" href=\"https:\/\/www.staffsante.fr\/contenu\/wp-content\/uploads\/2018\/02\/lettre-de-motivation-pharmacien.doc\">Exemple lettre de motivation Pharmacien<\/a><\/p>\n<p>Votre lettre de motivation de pharmacien est termin\u00e9e ? Consultez notre <a title=\"Un exemple de CV Pharmacien\" href=\"https:\/\/content.staffsante.fr\/exemple-cv-pharmacien\/\">exemple de CV<\/a> et toutes les <a title=\"Les offres d'emploi pour pharmacien\" href=\"https:\/\/www.staffsante.fr\/offres-emploi-m-pharmacien\">offres d\u2019emploi de pharmacien<\/a> et postulez !<\/p>\n<h2>Trouvez votre prochain emploi de pharmacien<\/h2>\n<div id=\"result_extract\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lettre de motivation pharmacien Vous recherchez un exemple de lettre de motivation pour pharmacien\u00a0? Retrouvez sur cette page nos conseils et un exemple de lettre de motivation pour une candidature [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[303,121,105],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exemple, mod\u00e8le de lettre de motivation Pharmacien | STAFFSANT\u00c9<\/title>\n<meta name=\"description\" content=\"\u00c0 la recherche d\u2019un exemple de lettre de motivation pour pharmacien? Consultez notre exemple en ligne et nos conseils : simple et efficace pour \u00eatre recrut\u00e9 \u00e0 coup s\u00fbr !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exemple, mod\u00e8le de lettre de motivation Pharmacien | STAFFSANT\u00c9\" \/>\n<meta property=\"og:description\" content=\"\u00c0 la recherche d\u2019un exemple de lettre de motivation pour pharmacien? Consultez notre exemple en ligne et nos conseils : simple et efficace pour \u00eatre recrut\u00e9 \u00e0 coup s\u00fbr !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/\" \/>\n<meta property=\"og:site_name\" content=\"STAFFSANT\u00c9\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-07T15:39:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T14:56:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2018\/02\/lettre-de-motivation-pharmacien.png\" \/>\n<meta name=\"author\" content=\"admin_staff_content\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_staff_content\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/\"},\"author\":{\"name\":\"admin_staff_content\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/8cea5b012277ab5dd4995aec10f20b0c\"},\"headline\":\"Exemple de lettre de motivation pharmacien\u00a0: officine et hospitalier\",\"datePublished\":\"2018-02-07T15:39:42+00:00\",\"dateModified\":\"2026-04-22T14:56:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/\"},\"wordCount\":584,\"publisher\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#organization\"},\"keywords\":[\"lettre de motivation\",\"pharmaciens\",\"postuler\"],\"articleSection\":[\"Exemples de CV et de lettres de motivation\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/\",\"url\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/\",\"name\":\"Exemple, mod\u00e8le de lettre de motivation Pharmacien | STAFFSANT\u00c9\",\"isPartOf\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#website\"},\"datePublished\":\"2018-02-07T15:39:42+00:00\",\"dateModified\":\"2026-04-22T14:56:32+00:00\",\"description\":\"\u00c0 la recherche d\u2019un exemple de lettre de motivation pour pharmacien? Consultez notre exemple en ligne et nos conseils : simple et efficace pour \u00eatre recrut\u00e9 \u00e0 coup s\u00fbr !\",\"breadcrumb\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.staffsante.fr\/contenu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exemple de lettre de motivation pharmacien\u00a0: officine et hospitalier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#website\",\"url\":\"https:\/\/www.staffsante.fr\/contenu\/\",\"name\":\"STAFFSANT\u00c9\",\"description\":\"L&#039;actualit\u00e9 carri\u00e8re des professionnels de sant\u00e9\",\"publisher\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.staffsante.fr\/contenu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#organization\",\"name\":\"Staffsant\u00e9\",\"url\":\"https:\/\/www.staffsante.fr\/contenu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2017\/06\/Staffsante.jpg\",\"contentUrl\":\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2017\/06\/Staffsante.jpg\",\"width\":2225,\"height\":592,\"caption\":\"Staffsant\u00e9\"},\"image\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/8cea5b012277ab5dd4995aec10f20b0c\",\"name\":\"admin_staff_content\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/2b9ac03912eb39091678a45d1b4c36c0?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/2b9ac03912eb39091678a45d1b4c36c0?s=96&d=mm&r=g\",\"caption\":\"admin_staff_content\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exemple, mod\u00e8le de lettre de motivation Pharmacien | STAFFSANT\u00c9","description":"\u00c0 la recherche d\u2019un exemple de lettre de motivation pour pharmacien? Consultez notre exemple en ligne et nos conseils : simple et efficace pour \u00eatre recrut\u00e9 \u00e0 coup s\u00fbr !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/","og_locale":"fr_FR","og_type":"article","og_title":"Exemple, mod\u00e8le de lettre de motivation Pharmacien | STAFFSANT\u00c9","og_description":"\u00c0 la recherche d\u2019un exemple de lettre de motivation pour pharmacien? Consultez notre exemple en ligne et nos conseils : simple et efficace pour \u00eatre recrut\u00e9 \u00e0 coup s\u00fbr !","og_url":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/","og_site_name":"STAFFSANT\u00c9","article_published_time":"2018-02-07T15:39:42+00:00","article_modified_time":"2026-04-22T14:56:32+00:00","og_image":[{"url":"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2018\/02\/lettre-de-motivation-pharmacien.png"}],"author":"admin_staff_content","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin_staff_content","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/#article","isPartOf":{"@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/"},"author":{"name":"admin_staff_content","@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/8cea5b012277ab5dd4995aec10f20b0c"},"headline":"Exemple de lettre de motivation pharmacien\u00a0: officine et hospitalier","datePublished":"2018-02-07T15:39:42+00:00","dateModified":"2026-04-22T14:56:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/"},"wordCount":584,"publisher":{"@id":"https:\/\/www.staffsante.fr\/contenu\/#organization"},"keywords":["lettre de motivation","pharmaciens","postuler"],"articleSection":["Exemples de CV et de lettres de motivation"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/","url":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/","name":"Exemple, mod\u00e8le de lettre de motivation Pharmacien | STAFFSANT\u00c9","isPartOf":{"@id":"https:\/\/www.staffsante.fr\/contenu\/#website"},"datePublished":"2018-02-07T15:39:42+00:00","dateModified":"2026-04-22T14:56:32+00:00","description":"\u00c0 la recherche d\u2019un exemple de lettre de motivation pour pharmacien? Consultez notre exemple en ligne et nos conseils : simple et efficace pour \u00eatre recrut\u00e9 \u00e0 coup s\u00fbr !","breadcrumb":{"@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.staffsante.fr\/contenu\/exemple-lettre-de-motivation-pharmacien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.staffsante.fr\/contenu\/"},{"@type":"ListItem","position":2,"name":"Exemple de lettre de motivation pharmacien\u00a0: officine et hospitalier"}]},{"@type":"WebSite","@id":"https:\/\/www.staffsante.fr\/contenu\/#website","url":"https:\/\/www.staffsante.fr\/contenu\/","name":"STAFFSANT\u00c9","description":"L&#039;actualit\u00e9 carri\u00e8re des professionnels de sant\u00e9","publisher":{"@id":"https:\/\/www.staffsante.fr\/contenu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.staffsante.fr\/contenu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.staffsante.fr\/contenu\/#organization","name":"Staffsant\u00e9","url":"https:\/\/www.staffsante.fr\/contenu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/logo\/image\/","url":"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2017\/06\/Staffsante.jpg","contentUrl":"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2017\/06\/Staffsante.jpg","width":2225,"height":592,"caption":"Staffsant\u00e9"},"image":{"@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/8cea5b012277ab5dd4995aec10f20b0c","name":"admin_staff_content","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/2b9ac03912eb39091678a45d1b4c36c0?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/2b9ac03912eb39091678a45d1b4c36c0?s=96&d=mm&r=g","caption":"admin_staff_content"}}]}},"_links":{"self":[{"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/posts\/4561"}],"collection":[{"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/comments?post=4561"}],"version-history":[{"count":10,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/posts\/4561\/revisions"}],"predecessor-version":[{"id":12933,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/posts\/4561\/revisions\/12933"}],"wp:attachment":[{"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/media?parent=4561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/categories?post=4561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/tags?post=4561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}