

{"id":8980,"date":"2022-12-16T11:22:01","date_gmt":"2022-12-16T10:22:01","guid":{"rendered":"https:\/\/www.staffsante.fr\/contenu\/?p=8980"},"modified":"2023-11-28T11:37:18","modified_gmt":"2023-11-28T10:37:18","slug":"quelle-tenue-choisir-pour-un-entretien-dembauche","status":"publish","type":"post","link":"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/","title":{"rendered":"Quelle tenue choisir pour un entretien d&#8217;embauche ?"},"content":{"rendered":"<p>F\u00e9licitations, votre candidature a \u00e9t\u00e9 retenue pour un entretien ! Le jour J approche et une angoisse appara\u00eet : comment vais-je m&#8217;habiller ? Pas de panique ! Nous vous partageons nos conseils pour faire bonne impression d\u00e8s les premi\u00e8res minutes :<\/p>\n<h2>1) Choisissez une tenue dans laquelle vous \u00eates \u00e0 l\u2019aise<\/h2>\n<p>Oubliez les talons que vous ne portez qu\u2019une fois par an ou la chemise un peu trop serr\u00e9e que vous ne sortez pour les grandes occasions. Vous risquez d\u2019\u00eatre plus concentr\u00e9 sur les douleurs que vous procure vos chaussures que sur les questions du recruteur. <strong>Pensez \u00e0 votre confort pour \u00eatre dans les meilleures dispositions possibles.<\/strong><\/p>\n<h2>2) Privil\u00e9giez des couleurs sobres<\/h2>\n<p>\u00c0 choisir, privil\u00e9giez des tenues sobres. Chemise ou pull uni, veste, jean sans trous ou pantalon plus \u00ab\u00a0classique\u00a0\u00bb, robe noire, chaussures propres\u2026 le faux pas vestimentaire est impossible. N\u2019oubliez pas que le recruteur se fait une impression sur vous d\u00e8s votre arriv\u00e9e. <strong>Choisir une tenue sobre peut \u00e9viter qu\u2019il se focalise sur un d\u00e9tail extravagant de votre look, au d\u00e9triment de vos r\u00e9ponses.<\/strong><\/p>\n<h2>3) Renseignez-vous en amont<\/h2>\n<p>Si vous connaissez des personnes du service que vous souhaitez rejoindre, n\u2019h\u00e9sitez pas \u00e0 leur poser des questions. <strong>Comment sont les personnes qui seront pr\u00e9sentes lors de l\u2019entretien ?<\/strong> Quelle est l\u2019ambiance g\u00e9n\u00e9rale du service ? Cela peut vous orienter dans votre choix vestimentaire le jour J.<\/p>\n<h2>4) Soyez vous-m\u00eame<\/h2>\n<p>Enfin, restez vous m\u00eames ! <strong>Ne vous inventez pas un personnage que vous n\u2019\u00eates pas.<\/strong> Vous en serez plus confiant\u00b7e et assur\u00e9\u00b7e.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.staffsante.fr\/contenu\/category\/conseils\/\" target=\"_blank\" rel=\"noopener\">Retrouvez tous nos conseils en cliquant ici<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00e9licitations, votre candidature a \u00e9t\u00e9 retenue pour un entretien ! Le jour J approche et une angoisse appara\u00eet : comment vais-je m&#8217;habiller ? Pas de panique ! Nous vous partageons [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8982,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,28],"tags":[19,500,142],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quelle tenue choisir pour un entretien d&#039;embauche ? | STAFFSANT\u00c9<\/title>\n<meta name=\"description\" content=\"Le jour de l&#039;entretien approche et une angoisse appara\u00eet : comment vais-je m&#039;habiller? Pas de panique! Nous vous partageons nos conseils pour faire bonne impression d\u00e8s les premi\u00e8res minutes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quelle tenue choisir pour un entretien d&#039;embauche ? | STAFFSANT\u00c9\" \/>\n<meta property=\"og:description\" content=\"Le jour de l&#039;entretien approche et une angoisse appara\u00eet : comment vais-je m&#039;habiller? Pas de panique! Nous vous partageons nos conseils pour faire bonne impression d\u00e8s les premi\u00e8res minutes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/\" \/>\n<meta property=\"og:site_name\" content=\"STAFFSANT\u00c9\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-16T10:22:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T10:37:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2022\/12\/tenue-entretienembauche.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"217\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_staff_content\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_staff_content\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/\"},\"author\":{\"name\":\"admin_staff_content\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/8cea5b012277ab5dd4995aec10f20b0c\"},\"headline\":\"Quelle tenue choisir pour un entretien d&#8217;embauche ?\",\"datePublished\":\"2022-12-16T10:22:01+00:00\",\"dateModified\":\"2023-11-28T10:37:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/\"},\"wordCount\":279,\"publisher\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#organization\"},\"keywords\":[\"candidature\",\"carri\u00e8re\",\"entretien d'embauche\"],\"articleSection\":[\"Actualit\u00e9s\",\"G\u00e9rer sa carri\u00e8re\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/\",\"url\":\"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/\",\"name\":\"Quelle tenue choisir pour un entretien d'embauche ? | STAFFSANT\u00c9\",\"isPartOf\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#website\"},\"datePublished\":\"2022-12-16T10:22:01+00:00\",\"dateModified\":\"2023-11-28T10:37:18+00:00\",\"description\":\"Le jour de l'entretien approche et une angoisse appara\u00eet : comment vais-je m'habiller? Pas de panique! Nous vous partageons nos conseils pour faire bonne impression d\u00e8s les premi\u00e8res minutes\",\"breadcrumb\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.staffsante.fr\/contenu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quelle tenue choisir pour un entretien d&#8217;embauche ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#website\",\"url\":\"https:\/\/www.staffsante.fr\/contenu\/\",\"name\":\"STAFFSANT\u00c9\",\"description\":\"L&#039;actualit\u00e9 carri\u00e8re des professionnels de sant\u00e9\",\"publisher\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.staffsante.fr\/contenu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#organization\",\"name\":\"Staffsant\u00e9\",\"url\":\"https:\/\/www.staffsante.fr\/contenu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2017\/06\/Staffsante.jpg\",\"contentUrl\":\"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2017\/06\/Staffsante.jpg\",\"width\":2225,\"height\":592,\"caption\":\"Staffsant\u00e9\"},\"image\":{\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/8cea5b012277ab5dd4995aec10f20b0c\",\"name\":\"admin_staff_content\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/2b9ac03912eb39091678a45d1b4c36c0?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/2b9ac03912eb39091678a45d1b4c36c0?s=96&d=mm&r=g\",\"caption\":\"admin_staff_content\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quelle tenue choisir pour un entretien d'embauche ? | STAFFSANT\u00c9","description":"Le jour de l'entretien approche et une angoisse appara\u00eet : comment vais-je m'habiller? Pas de panique! Nous vous partageons nos conseils pour faire bonne impression d\u00e8s les premi\u00e8res minutes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/","og_locale":"fr_FR","og_type":"article","og_title":"Quelle tenue choisir pour un entretien d'embauche ? | STAFFSANT\u00c9","og_description":"Le jour de l'entretien approche et une angoisse appara\u00eet : comment vais-je m'habiller? Pas de panique! Nous vous partageons nos conseils pour faire bonne impression d\u00e8s les premi\u00e8res minutes","og_url":"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/","og_site_name":"STAFFSANT\u00c9","article_published_time":"2022-12-16T10:22:01+00:00","article_modified_time":"2023-11-28T10:37:18+00:00","og_image":[{"width":800,"height":217,"url":"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2022\/12\/tenue-entretienembauche.jpg","type":"image\/jpeg"}],"author":"admin_staff_content","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin_staff_content","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/#article","isPartOf":{"@id":"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/"},"author":{"name":"admin_staff_content","@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/8cea5b012277ab5dd4995aec10f20b0c"},"headline":"Quelle tenue choisir pour un entretien d&#8217;embauche ?","datePublished":"2022-12-16T10:22:01+00:00","dateModified":"2023-11-28T10:37:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/"},"wordCount":279,"publisher":{"@id":"https:\/\/www.staffsante.fr\/contenu\/#organization"},"keywords":["candidature","carri\u00e8re","entretien d'embauche"],"articleSection":["Actualit\u00e9s","G\u00e9rer sa carri\u00e8re"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/","url":"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/","name":"Quelle tenue choisir pour un entretien d'embauche ? | STAFFSANT\u00c9","isPartOf":{"@id":"https:\/\/www.staffsante.fr\/contenu\/#website"},"datePublished":"2022-12-16T10:22:01+00:00","dateModified":"2023-11-28T10:37:18+00:00","description":"Le jour de l'entretien approche et une angoisse appara\u00eet : comment vais-je m'habiller? Pas de panique! Nous vous partageons nos conseils pour faire bonne impression d\u00e8s les premi\u00e8res minutes","breadcrumb":{"@id":"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.staffsante.fr\/contenu\/quelle-tenue-choisir-pour-un-entretien-dembauche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.staffsante.fr\/contenu\/"},{"@type":"ListItem","position":2,"name":"Quelle tenue choisir pour un entretien d&#8217;embauche ?"}]},{"@type":"WebSite","@id":"https:\/\/www.staffsante.fr\/contenu\/#website","url":"https:\/\/www.staffsante.fr\/contenu\/","name":"STAFFSANT\u00c9","description":"L&#039;actualit\u00e9 carri\u00e8re des professionnels de sant\u00e9","publisher":{"@id":"https:\/\/www.staffsante.fr\/contenu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.staffsante.fr\/contenu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.staffsante.fr\/contenu\/#organization","name":"Staffsant\u00e9","url":"https:\/\/www.staffsante.fr\/contenu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/logo\/image\/","url":"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2017\/06\/Staffsante.jpg","contentUrl":"https:\/\/content.staffsante.fr\/wp-content\/uploads\/2017\/06\/Staffsante.jpg","width":2225,"height":592,"caption":"Staffsant\u00e9"},"image":{"@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/8cea5b012277ab5dd4995aec10f20b0c","name":"admin_staff_content","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.staffsante.fr\/contenu\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/2b9ac03912eb39091678a45d1b4c36c0?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/2b9ac03912eb39091678a45d1b4c36c0?s=96&d=mm&r=g","caption":"admin_staff_content"}}]}},"_links":{"self":[{"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/posts\/8980"}],"collection":[{"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/comments?post=8980"}],"version-history":[{"count":2,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/posts\/8980\/revisions"}],"predecessor-version":[{"id":8984,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/posts\/8980\/revisions\/8984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/media\/8982"}],"wp:attachment":[{"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/media?parent=8980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/categories?post=8980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.staffsante.fr\/contenu\/wp-json\/wp\/v2\/tags?post=8980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}